{"id":7958,"date":"2022-04-28T09:26:21","date_gmt":"2022-04-28T09:26:21","guid":{"rendered":"https:\/\/purple-vest.net\/information\/sequence-accessible\/"},"modified":"2023-01-17T07:17:21","modified_gmt":"2023-01-17T07:17:21","slug":"sequence-accessible","status":"publish","type":"information","link":"https:\/\/purple-vest.net\/fr\/information\/sequence-accessible\/","title":{"rendered":"S\u00e9quence accessible"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Assistance accessible aux personnes handicap\u00e9es et aux personnes \u00e2g\u00e9es<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Patience, assistance et sensibilit\u00e9<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Principes de base pour offrir un service accessible<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les personnes handicap\u00e9es esp\u00e8rent que leurs besoins soient pris en compte.<\/li>\n\n\n\n<li>Le plus souvent, le handicap n&rsquo;est pas visible. <\/li>\n\n\n\n<li>Les personnes handicap\u00e9es arrivent souvent avec un accompagnateur. Discutez toujours avec la personne handicap\u00e9e et non avec son accompagnateur. <\/li>\n\n\n\n<li>Les aides \u00e0 la mobilit\u00e9 (comme les fauteuils roulants, les d\u00e9ambulateurs, les b\u00e9quilles, les cannes d&rsquo;aveugle, les chiens-guides) font partie int\u00e9grante de l&rsquo;espace priv\u00e9 de l\u2019handicap\u00e9e. Ne les touchez pas, ne vous penchez pas vers eux et ne les d\u00e9placez pas sans leur permission. <\/li>\n\n\n\n<li>Les personnes handicap\u00e9es (pas seulement les aveugles) sont autoris\u00e9es \u00e0 entrer \u00e0 tout moment dans tout lieu public avec un chien-guide.<\/li>\n\n\n\n<li>La meilleure fa\u00e7on d&rsquo;aider une personne handicap\u00e9e est de lui demander de quel type d&rsquo;aide elle a besoin et de l\u2019\u00e9couter parler et s&rsquo;expliquer. <\/li>\n\n\n\n<li> Veillez \u00e0 \u00eatre poli, sensible et patient.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Principes pour la fourniture d&rsquo;une assistance accessible aux personnes souffrant d&rsquo;un handicap auditif<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Signes permettant d&rsquo;identifier une personne souffrant d&rsquo;un handicap auditif : <\/strong>Une personne souffrant d&rsquo;un handicap auditif vous demandera fr\u00e9quemment de r\u00e9p\u00e9ter ce que vous dites, vous demandera de parler plus fort, ne comprendra pas ce que vous dites, fixera vos l\u00e8vres lorsque vous parlerez ; les personnes \u00e2g\u00e9es souffrent g\u00e9n\u00e9ralement de d\u00e9ficience auditive. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Signes permettant d&rsquo;identifier une personne sourde<\/strong><strong> : <\/strong>Difficult\u00e9 de langage, parole peu claire, utilise le langage des signes, ne r\u00e9agit pas quand on lui parle. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Guide pour une assistance accessible : <\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Faites face \u00e0 la personne lorsque vous lui parlez. Ne cachez pas votre bouche pendant que vous parlez pour lui permettre de lire sur vos l\u00e8vres.<\/li>\n\n\n\n<li>Parlez lentement et clairement et n&rsquo;exag\u00e9rez pas vos mimiques. <\/li>\n\n\n\n<li>Veuillez ne pas crier Crier ne rime \u00e0 rien et provoque des douleurs dans les oreilles des personnes portant des appareils auditifs. <\/li>\n\n\n\n<li>Si vous souhaitez attirer l&rsquo;attention de votre interlocuteur, touchez-lui d\u00e9licatement l&rsquo;\u00e9paule. <\/li>\n\n\n\n<li>Vous pouvez \u00e9crire ce que vous avez a dire sur une feuille de papier ou sur votre t\u00e9l\u00e9phone portable <\/li>\n\n\n\n<li>Si vous avez du mal \u00e0 vous faire comprendre par les mots, utilisez les gestes. Ne faites pas semblant de comprendre. Demandez-lui de r\u00e9p\u00e9ter ce qu&rsquo;il a dit. <\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Principes pour offrir une assistance accessible aux personnes ayant un handicap visuel<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Signe d&rsquo;identification<\/strong> : Utilise une canne blanche ou un chien guide, utilise sa main pour toucher et identifier les objets, demande de l&rsquo;aide pour identifier des objets (un document, de l&rsquo;argent et autres), marche tr\u00e8s lentement et avec pr\u00e9caution. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Guide pour une assistance accessible : <\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Entrer dans un lieu public avec un chien-guide leur est toujours autoris\u00e9. \u00c9vitez de chercher \u00e0 caresser le chien-guide.<\/li>\n\n\n\n<li>Veillez \u00e0 ce que les voies ne soient pas encombr\u00e9es. <\/li>\n\n\n\n<li>Demandez \u00e0 la personne comment l&rsquo;escorter si n\u00e9cessaire. G\u00e9n\u00e9ralement, la personne vous tient par le coude ou pose sa main sur votre \u00e9paule et vous laisse la diriger. <\/li>\n\n\n\n<li>d\u00e9crire le parcours (&nbsp;\u00ab&nbsp;Il y a deux marches devant toi\u00a0\u00bb ; \u00ab&nbsp;Maintenant, on tourne \u00e0 droite&nbsp;\u00bb.), l&rsquo;environnement et les situations ou bruits non verbaux.<\/li>\n\n\n\n<li>\u00c9vitez de toucher la canne blanche ou les objets personnels de la personne. Si n\u00e9cessaire, pensez \u00e0 obtenir son autorisation.<\/li>\n\n\n\n<li>lire des informations \u00e9crites et d\u00e9crire les images ou signes.<\/li>\n\n\n\n<li>Aider \u00e0 remplir les formulaires.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Principes de base pour offrir une assistance accessible aux personnes souffrant d&rsquo;un handicap physique<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Signes d&rsquo;identification&nbsp;: <\/strong>la personne se sert d&rsquo;un fauteuil roulant, d&rsquo;un scooter \u00e9lectrique, d&rsquo;une marchette ou de b\u00e9quilles. La personne boite, marche lentement, pr\u00e9sente une d\u00e9ficience au niveau des mains.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> les personnes \u00e2g\u00e9e pr\u00e9sente g\u00e9n\u00e9ralement des handicaps physiques.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Guide pour une assistance accessible : <\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Veillez \u00e0 ce que les personnes \u00e0 mobilit\u00e9 r\u00e9duite aient acc\u00e8s \u00e0 votre bureau.<\/li>\n\n\n\n<li>Offrez votre aide aux enfants \u00e0 mobilit\u00e9 r\u00e9duite. Demandez-lui quel type d&rsquo;aide il pr\u00e9f\u00e8re. Ne vous dites pas tout de suite que vous savez comment les aider.<\/li>\n\n\n\n<li>Faites en sorte que les couloirs soient libres de tout objet et que les salles d&rsquo;attente soient assez larges et spacieuses.<\/li>\n\n\n\n<li>Proposez au client de l&rsquo;aider \u00e0 payer ou de lui pr\u00e9senter des documents s&rsquo;il utilise un d\u00e9ambulateur ou des b\u00e9quilles. <\/li>\n\n\n\n<li>Si la personne se d\u00e9place en fauteuil roulant, veillez \u00e0 d\u00e9placer les chaises pour qu&rsquo;elle ait suffisamment d&rsquo;espace pour passer avec son fauteuil. <\/li>\n\n\n\n<li>Si la personne souffre d&rsquo;un handicap li\u00e9 \u00e0 la marche, offrez-lui une chaise avec des poign\u00e9es. <\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Principes pour offrir une assistance accessible aux personnes pr\u00e9sentant des difficult\u00e9s de communication\/cognitives ou mentales<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Signes permettant d&rsquo;identifier une personne pr\u00e9sentant un handicap cognitif (par exemple, une d\u00e9ficience intellectuelle), un autisme ou un handicap mental :<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La personne peut se montrer h\u00e9sitante, confuse, stress\u00e9e et anxieuse ou \u00eatre tr\u00e8s \u00e9motive et avoir du mal \u00e0 contr\u00f4ler ses actions ou r\u00e9actions. <\/li>\n\n\n\n<li>La personne a des difficult\u00e9s \u00e0 comprendre les situations et a besoin de faire appel \u00e0 une tierce personne <\/li>\n\n\n\n<li>La personne a du mal \u00e0 communiquer ou \u00e0 s&rsquo;expliquer.<\/li>\n\n\n\n<li>temps de r\u00e9action lent.<\/li>\n\n\n\n<li>Elle peut se r\u00e9p\u00e9ter (r\u00e9p\u00e9ter la m\u00eame question, r\u00e9p\u00e9ter une m\u00eame phrase ou un m\u00eame geste). <\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Guide pour une assistance accessible : <\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00c9coutez patiemment, car il est possible que la personne ait besoin de plus de temps pour s&rsquo;exprimer.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Concentrez-vous sur ce que la personne dit et non sur la mani\u00e8re dont elle le dit ou parle.<\/li>\n\n\n\n<li>Faites des phrases courtes avec des mots simples, courants et fr\u00e9quents. Donnez des exemples de ce que vous dites. <\/li>\n\n\n\n<li>N&rsquo;h\u00e9sitez pas \u00e0 demander aux personnes ayant des capacit\u00e9s de communication diff\u00e9rentes de r\u00e9p\u00e9ter ce qu&rsquo;elles ont dit si vous n&rsquo;avez pas compris. <\/li>\n\n\n\n<li>Pour \u00e9viter tous malentendus, assurez-vous d&rsquo;avoir bien compris. <\/li>\n\n\n\n<li>\u00c9vitez de supposer, ne compl\u00e9tez pas les phrases de votre interlocuteur et ne le brusquez pas.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Laissez la personne choisir et d\u00e9cider par elle-m\u00eame.<\/li>\n\n\n\n<li>Soyez patient et sensible. <\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Contactez-nous&nbsp;:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Email: <a href=\"mailto:pvm@aisrael.org\">pvm@aisrael.org<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Num\u00e9ro de t\u00e9l\u00e9phone mobile&nbsp;: +972-543445596<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Site Internet : <a href=\"http:\/\/www.purple-vest.com\">www.purple-vest.com<\/a><\/p>\n","protected":false},"template":"","class_list":["post-7958","information","type-information","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00e9quence accessible | Purple Vest Mission<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/purple-vest.net\/fr\/information\/sequence-accessible\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e9quence accessible | Purple Vest Mission\" \/>\n<meta property=\"og:description\" content=\"Assistance accessible aux personnes handicap\u00e9es et aux personnes \u00e2g\u00e9es Patience, assistance et sensibilit\u00e9 Principes de base pour offrir un service accessible Principes pour la fourniture d&rsquo;une assistance accessible aux personnes souffrant d&rsquo;un handicap auditif Signes permettant d&rsquo;identifier une personne souffrant d&rsquo;un handicap auditif : Une personne souffrant d&rsquo;un handicap auditif vous demandera fr\u00e9quemment de r\u00e9p\u00e9ter [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/purple-vest.net\/fr\/information\/sequence-accessible\/\" \/>\n<meta property=\"og:site_name\" content=\"Purple Vest Mission\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Negishut.Israel\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-17T07:17:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/purple-vest.net\/wp-content\/uploads\/2022\/05\/b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"876\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AccessIL\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/purple-vest.net\\\/fr\\\/information\\\/sequence-accessible\\\/\",\"url\":\"https:\\\/\\\/purple-vest.net\\\/fr\\\/information\\\/sequence-accessible\\\/\",\"name\":\"S\u00e9quence accessible | Purple Vest Mission\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/purple-vest.net\\\/#website\"},\"datePublished\":\"2022-04-28T09:26:21+00:00\",\"dateModified\":\"2023-01-17T07:17:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/purple-vest.net\\\/fr\\\/information\\\/sequence-accessible\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/purple-vest.net\\\/fr\\\/information\\\/sequence-accessible\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/purple-vest.net\\\/fr\\\/information\\\/sequence-accessible\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/purple-vest.net\\\/he\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Importamt Information\",\"item\":\"https:\\\/\\\/purple-vest.net\\\/information\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"S\u00e9quence accessible\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/purple-vest.net\\\/#website\",\"url\":\"https:\\\/\\\/purple-vest.net\\\/\",\"name\":\"Purple Vest Mission\",\"description\":\"Purple Vest Mission - Leave no one behind | By Access Israel | Supported by The Nippon Foundation\",\"publisher\":{\"@id\":\"https:\\\/\\\/purple-vest.net\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/purple-vest.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/purple-vest.net\\\/#organization\",\"name\":\"Purple Vest Mission\",\"url\":\"https:\\\/\\\/purple-vest.net\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/purple-vest.net\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/purple-vest.net\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Purple-Vest-Logo-finalxx.svg\",\"contentUrl\":\"https:\\\/\\\/purple-vest.net\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Purple-Vest-Logo-finalxx.svg\",\"width\":841,\"height\":216,\"caption\":\"Purple Vest Mission\"},\"image\":{\"@id\":\"https:\\\/\\\/purple-vest.net\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Negishut.Israel\",\"https:\\\/\\\/x.com\\\/AccessIL\",\"https:\\\/\\\/www.instagram.com\\\/negishut_israel\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AisraelORG#pu\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00e9quence accessible | Purple Vest Mission","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/purple-vest.net\/fr\/information\/sequence-accessible\/","og_locale":"fr_FR","og_type":"article","og_title":"S\u00e9quence accessible | Purple Vest Mission","og_description":"Assistance accessible aux personnes handicap\u00e9es et aux personnes \u00e2g\u00e9es Patience, assistance et sensibilit\u00e9 Principes de base pour offrir un service accessible Principes pour la fourniture d&rsquo;une assistance accessible aux personnes souffrant d&rsquo;un handicap auditif Signes permettant d&rsquo;identifier une personne souffrant d&rsquo;un handicap auditif : Une personne souffrant d&rsquo;un handicap auditif vous demandera fr\u00e9quemment de r\u00e9p\u00e9ter [&hellip;]","og_url":"https:\/\/purple-vest.net\/fr\/information\/sequence-accessible\/","og_site_name":"Purple Vest Mission","article_publisher":"https:\/\/www.facebook.com\/Negishut.Israel","article_modified_time":"2023-01-17T07:17:21+00:00","og_image":[{"width":876,"height":682,"url":"https:\/\/purple-vest.net\/wp-content\/uploads\/2022\/05\/b.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AccessIL","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/purple-vest.net\/fr\/information\/sequence-accessible\/","url":"https:\/\/purple-vest.net\/fr\/information\/sequence-accessible\/","name":"S\u00e9quence accessible | Purple Vest Mission","isPartOf":{"@id":"https:\/\/purple-vest.net\/#website"},"datePublished":"2022-04-28T09:26:21+00:00","dateModified":"2023-01-17T07:17:21+00:00","breadcrumb":{"@id":"https:\/\/purple-vest.net\/fr\/information\/sequence-accessible\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/purple-vest.net\/fr\/information\/sequence-accessible\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/purple-vest.net\/fr\/information\/sequence-accessible\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/purple-vest.net\/he\/"},{"@type":"ListItem","position":2,"name":"Importamt Information","item":"https:\/\/purple-vest.net\/information\/"},{"@type":"ListItem","position":3,"name":"S\u00e9quence accessible"}]},{"@type":"WebSite","@id":"https:\/\/purple-vest.net\/#website","url":"https:\/\/purple-vest.net\/","name":"Purple Vest Mission","description":"Purple Vest Mission - Leave no one behind | By Access Israel | Supported by The Nippon Foundation","publisher":{"@id":"https:\/\/purple-vest.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/purple-vest.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/purple-vest.net\/#organization","name":"Purple Vest Mission","url":"https:\/\/purple-vest.net\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/purple-vest.net\/#\/schema\/logo\/image\/","url":"https:\/\/purple-vest.net\/wp-content\/uploads\/2022\/05\/Purple-Vest-Logo-finalxx.svg","contentUrl":"https:\/\/purple-vest.net\/wp-content\/uploads\/2022\/05\/Purple-Vest-Logo-finalxx.svg","width":841,"height":216,"caption":"Purple Vest Mission"},"image":{"@id":"https:\/\/purple-vest.net\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Negishut.Israel","https:\/\/x.com\/AccessIL","https:\/\/www.instagram.com\/negishut_israel\/","https:\/\/www.youtube.com\/user\/AisraelORG#pu"]}]}},"_links":{"self":[{"href":"https:\/\/purple-vest.net\/fr\/wp-json\/wp\/v2\/information\/7958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/purple-vest.net\/fr\/wp-json\/wp\/v2\/information"}],"about":[{"href":"https:\/\/purple-vest.net\/fr\/wp-json\/wp\/v2\/types\/information"}],"wp:attachment":[{"href":"https:\/\/purple-vest.net\/fr\/wp-json\/wp\/v2\/media?parent=7958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}